{"id":4279,"date":"2022-11-05T12:00:00","date_gmt":"2022-11-05T05:00:00","guid":{"rendered":"https:\/\/xzeeds.com\/?p=4279"},"modified":"2022-11-04T22:58:11","modified_gmt":"2022-11-04T15:58:11","slug":"%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1","status":"publish","type":"post","link":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e31\u0e1a\u0e40\u0e22\u0e47\u0e14\u0e08\u0e19\u0e19\u0e49\u0e33\u0e41\u0e15\u0e01\u0e04\u0e32\u0e23\u0e39\u0e2b\u0e35"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15-1024x683.jpg\" alt=\"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e2d\u0e48\u0e32\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e40\u0e25\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e2718+\" class=\"wp-image-4280\" srcset=\"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15-1024x683.jpg 1024w, https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15-300x200.jpg 300w, https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15-768x512.jpg 768w, https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27<\/figcaption><\/figure>\n\n\n\n<p><strong>\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e31\u0e1a\u0e40\u0e22\u0e47\u0e14\u0e08\u0e19\u0e19\u0e49\u0e33\u0e41\u0e15\u0e01\u0e04\u0e32\u0e23\u0e39\u0e2b\u0e35<\/strong><\/p>\n<p><a title=\"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27\" href=\"https:\/\/xzeeds.com\/\"><strong>\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27<\/strong><\/a> \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e25\u0e32\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e2b\u0e19\u0e35\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e21\u0e32\u0e2b\u0e32\u0e07\u0e32\u0e19\u0e17\u0e33\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e1e\u0e2d\u0e08\u0e30\u0e44\u0e1b\u0e27\u0e31\u0e14\u0e44\u0e1b\u0e27\u0e32\u0e01\u0e31\u0e1a\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19 \u0e40\u0e25\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22\u0e21\u0e32\u0e08\u0e35\u0e1a\u0e09\u0e31\u0e19\u0e1a\u0e48\u0e2d\u0e22\u0e46 \u0e41\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e15\u0e48\u0e04\u0e19\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e16\u0e39\u0e01\u0e43\u0e08\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e21\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e0a\u0e48\u0e32\u0e07\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e22\u0e38\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e09\u0e31\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e15\u0e48\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e02\u0e22\u0e31\u0e1a \u0e04\u0e32\u0e23\u0e21\u0e04\u0e21\u0e04\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e17\u0e35\u0e48\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e14\u0e35 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e09\u0e31\u0e19\u0e41\u0e2d\u0e1a\u0e2b\u0e25\u0e07\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27<\/p>\n<p>\u0e27\u0e31\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e2d\u0e01 \u0e40\u0e02\u0e32\u0e21\u0e32\u0e2b\u0e32\u0e09\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e09\u0e31\u0e19\u0e40\u0e0a\u0e48\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e21\u0e48\u0e44\u0e01\u0e25\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e40\u0e23\u0e32\u0e14\u0e37\u0e48\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e08\u0e19\u0e40\u0e21\u0e32 \u0e40\u0e02\u0e32\u0e02\u0e2d\u0e09\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1f\u0e19 \u0e41\u0e15\u0e48\u0e27\u0e48\u0e32\u0e09\u0e31\u0e19\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e14\u0e39\u0e43\u0e08\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e43\u0e08\u0e07\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e15\u0e2d\u0e19\u0e40\u0e23\u0e32\u0e19\u0e31\u0e48\u0e07\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19 \u0e40\u0e02\u0e32\u0e43\u0e2a\u0e48\u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e1a\u0e2d\u0e25\u0e02\u0e32\u0e2a\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e09\u0e31\u0e19\u0e01\u0e47\u0e40\u0e2d\u0e32\u0e41\u0e15\u0e48\u0e41\u0e2d\u0e1a\u0e21\u0e2d\u0e07\u0e25\u0e33\u0e04\u0e27\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e49\u0e32\u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e15\u0e38\u0e07\u0e46 \u0e19\u0e31\u0e49\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e04\u0e34\u0e14\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e02\u0e31\u0e49\u0e19\u0e27\u0e48\u0e32 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e22\u0e47\u0e14\u0e01\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e0b\u0e49\u0e33<\/p>\n<p>\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e48\u0e22\u0e19\u0e21\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2d\u0e32\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e44\u0e14\u0e49\u0e22\u0e32\u0e01\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e09\u0e31\u0e19\u0e40\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e1b\u0e0f\u0e34\u0e40\u0e2a\u0e18\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e08\u0e23\u0e34\u0e07\u0e46 &#8211; \u0e41\u0e15\u0e48\u0e40\u0e02\u0e32\u0e01\u0e47\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e08\u0e35\u0e1a\u0e09\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e19\u0e30 \u0e08\u0e19\u0e09\u0e31\u0e19\u0e40\u0e2d\u0e07\u0e01\u0e47\u0e40\u0e07\u0e35\u0e48\u0e22\u0e19\u0e21\u0e32\u0e01\u0e46 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e22\u0e31\u0e07\u0e44\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e32\u0e44\u0e14\u0e49\u0e40\u0e22\u0e47\u0e14\u0e09\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2d\u0e48\u0e22\u0e1b\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e09\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19\u0e1a\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e44\u0e1b\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e14\u0e39\u0e43\u0e08\u0e01\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e21\u0e32\u0e1e\u0e25\u0e34\u0e01\u0e25\u0e34\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e01\u0e47\u0e04\u0e07\u0e14\u0e39\u0e44\u0e21\u0e48\u0e14\u0e35<\/p>\n<p>\u0e09\u0e31\u0e19\u0e40\u0e25\u0e22\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e14\u0e37\u0e48\u0e21\u0e40\u0e2b\u0e25\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e40\u0e21\u0e32\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e41\u0e01\u0e25\u0e49\u0e07\u0e17\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e2d\u0e2d\u0e48\u0e2d\u0e19 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e41\u0e01\u0e25\u0e49\u0e07\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1c\u0e25\u0e47\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e1a\u0e44\u0e1b \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e19\u0e31\u0e49\u0e19\u0e43\u0e08\u0e2a\u0e31\u0e48\u0e19\u0e23\u0e30\u0e23\u0e34\u0e01\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e30\u0e40\u0e25\u0e22 \u0e40\u0e02\u0e32\u0e40\u0e14\u0e34\u0e19\u0e21\u0e32\u0e19\u0e31\u0e48\u0e07\u0e02\u0e49\u0e32\u0e07\u0e46 \u0e09\u0e31\u0e19 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e02\u0e22\u0e48\u0e32\u0e41\u0e02\u0e19\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e0a\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e32\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e25\u0e39\u0e1a\u0e44\u0e25\u0e49\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19&nbsp;<\/p>\n<p>\u0e43\u0e19\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e09\u0e31\u0e19\u0e22\u0e34\u0e49\u0e21\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e19\u0e43\u0e08\u0e40\u0e25\u0e22\u0e17\u0e35\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e21\u0e48\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e08\u0e30\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e04\u0e34\u0e14\u0e08\u0e23\u0e34\u0e07\u0e46&nbsp;<\/p>\n<p>\u0e40\u0e02\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e39\u0e1a\u0e09\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e22\u0e31\u0e07\u0e2b\u0e25\u0e31\u0e1a\u0e2d\u0e22\u0e39\u0e48 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e25\u0e27\u0e19\u0e25\u0e32\u0e21 \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e01\u0e09\u0e31\u0e19 \u0e2a\u0e2d\u0e14\u0e21\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e15\u0e49\u0e0a\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e0b\u0e38\u0e01\u0e44\u0e0b\u0e49\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e25\u0e21\u0e2b\u0e32\u0e22\u0e43\u0e08\u0e2b\u0e19\u0e31\u0e01\u0e46 \u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e40\u0e07\u0e35\u0e48\u0e22\u0e19\u0e21\u0e32\u0e01\u0e46 \u0e41\u0e15\u0e48\u0e21\u0e31\u0e19\u0e22\u0e32\u0e01\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e40\u0e01\u0e47\u0e1a\u0e2d\u0e32\u0e23\u0e21\u0e13\u0e4c\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49 \u0e44\u0e21\u0e48\u0e44\u0e2b\u0e25\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e31\u0e49\u0e19\u0e17\u0e38\u0e01\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e21\u0e31\u0e19\u0e08\u0e30\u0e1e\u0e31\u0e07\u0e08\u0e19\u0e2b\u0e21\u0e14<\/p>\n<p>\u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e17\u0e35\u0e48\u0e40\u0e02\u0e32\u0e04\u0e48\u0e2d\u0e22\u0e46 \u0e2a\u0e2d\u0e14\u0e19\u0e34\u0e49\u0e27\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e39\u0e2b\u0e35\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e02\u0e22\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e2d\u0e01<\/p>\n<p>\u0e09\u0e31\u0e19\u0e44\u0e21\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e17\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e27\u0e2b\u0e35\u0e44\u0e14\u0e49 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e25\u0e49\u0e32\u0e42\u0e25\u0e21\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e09\u0e31\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e15\u0e32\u0e21\u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e17\u0e19\u0e44\u0e2b\u0e27<\/p>\n<p>\u0e09\u0e31\u0e19\u0e04\u0e23\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e17\u0e31\u0e19\u0e17\u0e35\u0e41\u0e25\u0e49\u0e27\u0e25\u0e37\u0e21\u0e15\u0e32\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e02\u0e32\u0e40\u0e2d\u0e32\u0e21\u0e37\u0e2d\u0e21\u0e32\u0e1b\u0e34\u0e14\u0e1b\u0e32\u0e01\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e44\u0e27\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32 \u0e40\u0e02\u0e32\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e09\u0e31\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e1a\u0e32\u0e19\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e48\u0e2d\u0e19\u0e42\u0e22\u0e19 \u0e40\u0e02\u0e32\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e09\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e02\u0e32\u0e01\u0e47\u0e02\u0e22\u0e31\u0e1a\u0e19\u0e34\u0e49\u0e27\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e21\u0e2a\u0e2d\u0e14\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e39\u0e2b\u0e35\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e25\u0e21\u0e2b\u0e32\u0e22\u0e43\u0e08\u0e17\u0e35\u0e48\u0e02\u0e32\u0e14\u0e2b\u0e49\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e27\u0e2b\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e09\u0e31\u0e19\u0e1e\u0e22\u0e31\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e31\u0e19\u0e17\u0e35<\/p>\n<p>\u0e40\u0e02\u0e32\u0e22\u0e34\u0e49\u0e21\u0e2d\u0e2d\u0e01 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e14\u0e36\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e25\u0e35\u0e22\u0e01\u0e34\u0e19\u0e19\u0e49\u0e33\u0e40\u0e07\u0e35\u0e48\u0e22\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e2b\u0e35\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e08\u0e31\u0e1a\u0e02\u0e32\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e41\u0e22\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e49\u0e27\u0e40\u0e25\u0e35\u0e22\u0e2b\u0e35\u0e43\u0e2b\u0e49\u0e09\u0e31\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35<\/p>\n<p>\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e25\u0e35\u0e22\u0e2b\u0e35\u0e17\u0e35\u0e48\u0e14\u0e39\u0e15\u0e30\u0e01\u0e25\u0e30\u0e15\u0e30\u0e01\u0e25\u0e32\u0e21\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e19\u0e21\u0e39\u0e21\u0e21\u0e32\u0e21\u0e19\u0e31\u0e49\u0e19\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e09\u0e31\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e23 \u0e1b\u0e25\u0e14\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e04\u0e23\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e2d\u0e31\u0e49\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e2d\u0e35\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e35\u0e22\u0e27\u0e25\u0e34\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e02\u0e22\u0e31\u0e1a\u0e44\u0e2b\u0e27\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e2d\u0e07\u0e28\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e27\u0e0b\u0e48\u0e32\u0e19\u0e16\u0e39\u0e01\u0e40\u0e02\u0e32\u0e21\u0e2d\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48 \u0e2b\u0e35\u0e0a\u0e21\u0e1e\u0e39\u0e16\u0e39\u0e01\u0e40\u0e02\u0e32\u0e14\u0e39\u0e14\u0e14\u0e38\u0e19 \u0e40\u0e21\u0e47\u0e14\u0e41\u0e15\u0e14\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e15\u0e01\u0e47\u0e16\u0e39\u0e01\u0e40\u0e02\u0e32\u0e2a\u0e30\u0e01\u0e34\u0e14\u0e40\u0e23\u0e49\u0e32\u0e2d\u0e32\u0e23\u0e21\u0e13\u0e4c\u0e08\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2a\u0e31\u0e48\u0e19\u0e23\u0e30\u0e23\u0e34\u0e01 \u0e09\u0e31\u0e19\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e02\u0e2d\u0e40\u0e02\u0e32\u0e2d\u0e21\u0e04\u0e27\u0e22 \u0e09\u0e31\u0e19\u0e2d\u0e22\u0e32\u0e01\u0e2d\u0e21\u0e04\u0e27\u0e22 \u0e41\u0e15\u0e48\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e2d\u0e30\u0e44\u0e23\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e34\u0e19\u0e22\u0e2d\u0e21\u0e44\u0e1b\u0e01\u0e48\u0e2d\u0e19<\/p>\n<p>\u0e40\u0e02\u0e32\u0e25\u0e38\u0e01\u0e02\u0e36\u0e49\u0e19\u0e22\u0e37\u0e19 \u0e16\u0e2d\u0e14\u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e1a\u0e2d\u0e25\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e49\u0e32\u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e15\u0e38\u0e07 \u0e17\u0e31\u0e19\u0e17\u0e35\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e22\u0e40\u0e02\u0e32\u0e43\u0e08\u0e09\u0e31\u0e19\u0e40\u0e15\u0e49\u0e19\u0e41\u0e23\u0e07\u0e17\u0e31\u0e19\u0e17\u0e35<\/p>\n<p>\u0e40\u0e02\u0e32\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e32\u0e01 \u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e27\u0e48\u0e32\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e40\u0e04\u0e22\u0e40\u0e22\u0e47\u0e14\u0e21\u0e32\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e40\u0e2a\u0e35\u0e22\u0e2d\u0e35\u0e01<\/p>\n<p>\u0e40\u0e02\u0e32\u0e19\u0e31\u0e48\u0e07\u0e25\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e16\u0e2d\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2a\u0e25\u0e31\u0e01\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e30\u0e44\u0e23\u0e42\u0e22\u0e19\u0e17\u0e34\u0e49\u0e07\u0e44\u0e1b \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e25\u0e32\u0e22\u0e16\u0e39\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e2b\u0e31\u0e27\u0e04\u0e27\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e25\u0e37\u0e48\u0e19\u0e44\u0e2b\u0e25 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e04\u0e48\u0e2d\u0e22\u0e46 \u0e08\u0e31\u0e1a\u0e21\u0e31\u0e19\u0e14\u0e31\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e39\u0e2b\u0e35\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19<\/p>\n<p>\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e04\u0e37\u0e2d\u0e21\u0e31\u0e19\u0e40\u0e08\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e46 \u0e40\u0e08\u0e47\u0e1a\u0e08\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e1c\u0e25\u0e31\u0e01\u0e40\u0e02\u0e32\u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e07\u0e35\u0e48\u0e22\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e2b\u0e49\u0e32\u0e21\u0e44\u0e27\u0e49<\/p>\n<p>\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1c\u0e48\u0e2d\u0e19\u0e25\u0e21\u0e2b\u0e32\u0e22\u0e43\u0e08\u0e0a\u0e49\u0e32\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e32\u0e04\u0e48\u0e2d\u0e22\u0e46 \u0e14\u0e31\u0e19\u0e04\u0e27\u0e22\u0e19\u0e31\u0e49\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e39\u0e2b\u0e35\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e02\u0e32\u0e41\u0e2b\u0e07\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e49\u0e27\u0e04\u0e23\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e2b\u0e35\u0e09\u0e31\u0e19\u0e15\u0e2d\u0e14\u0e04\u0e27\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e2b\u0e19\u0e31\u0e01\u0e21\u0e32\u0e01 \u0e41\u0e15\u0e48\u0e09\u0e31\u0e19\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e1a\u0e2d\u0e01\u0e40\u0e02\u0e32\u0e27\u0e48\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e22\u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e32\u0e01\u0e46 \u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01<\/p>\n<p>\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e04\u0e23\u0e39\u0e48\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e25\u0e33\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e22\u0e32\u0e27\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e2a\u0e27\u0e21\u0e2a\u0e2d\u0e14\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08&nbsp;<\/p>\n<p>\u0e40\u0e02\u0e32\u0e42\u0e19\u0e49\u0e21\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e39\u0e1a\u0e41\u0e25\u0e49\u0e27\u0e40\u0e25\u0e49\u0e32\u0e42\u0e25\u0e21\u0e09\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e39\u0e48\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e02\u0e22\u0e31\u0e1a\u0e44\u0e2b\u0e27<\/p>\n<p>\u0e09\u0e31\u0e19\u0e17\u0e33\u0e43\u0e08\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e08\u0e47\u0e1a\u0e2d\u0e35\u0e01\u0e41\u0e19\u0e48 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e25\u0e48\u0e32\u0e40\u0e25\u0e22 \u0e09\u0e31\u0e19\u0e04\u0e34\u0e14\u0e1c\u0e34\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e17\u0e31\u0e19\u0e17\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e02\u0e22\u0e31\u0e1a\u0e44\u0e2b\u0e27\u0e40\u0e22\u0e47\u0e14\u0e2b\u0e35\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e19\u0e1f\u0e34\u0e15\u0e19\u0e31\u0e49\u0e19\u0e2b\u0e32\u0e22\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e27\u0e0b\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e25\u0e48\u0e2d\u0e07\u0e25\u0e2d\u0e22\u0e02\u0e36\u0e49\u0e19\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e41\u0e17\u0e19\u0e17\u0e35 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e27\u0e40\u0e1a\u0e32 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46&nbsp;<\/p>\n<p>\u0e40\u0e02\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 \u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01\u0e43\u0e2b\u0e49\u0e2b\u0e19\u0e31\u0e01\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e08\u0e19\u0e09\u0e31\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e49\u0e19\u0e2b\u0e32\u0e22\u0e43\u0e08 \u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e27\u0e0b\u0e48\u0e32\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e04\u0e23\u0e32\u0e07\u0e14\u0e31\u0e07\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e22\u0e46 \u0e22\u0e34\u0e48\u0e07\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e01\u0e23\u0e30\u0e40\u0e14\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e35\u0e48\u0e23\u0e31\u0e27\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e09\u0e31\u0e19\u0e22\u0e34\u0e48\u0e07\u0e04\u0e23\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e14\u0e31\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e27\u0e41\u0e17\u0e1a\u0e02\u0e32\u0e14\u0e43\u0e08 \u0e41\u0e15\u0e48\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e19\u0e31\u0e49\u0e19\u0e09\u0e31\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d<\/p>\n<p>\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e22\u0e47\u0e14\u0e2b\u0e35\u0e09\u0e31\u0e19\u0e41\u0e23\u0e07\u0e46 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e09\u0e31\u0e19\u0e40\u0e07\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e07\u0e35\u0e48\u0e22\u0e19\u0e08\u0e19\u0e17\u0e19\u0e44\u0e21\u0e48\u0e44\u0e2b\u0e27\u0e41\u0e25\u0e49\u0e27<\/p>\n<p>\u0e40\u0e02\u0e32\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e30\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 \u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e08\u0e31\u0e14\u0e40\u0e23\u0e35\u0e48\u0e22\u0e27\u0e41\u0e23\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e2d\u0e31\u0e14\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01\u0e40\u0e22\u0e47\u0e14\u0e09\u0e31\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e04\u0e23\u0e32\u0e07\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e23\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e48\u0e32\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e40\u0e01\u0e23\u0e47\u0e07\u0e41\u0e19\u0e48\u0e19 \u0e44\u0e21\u0e48\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e09\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e31\u0e1a\u0e15\u0e32\u0e41\u0e25\u0e49\u0e27\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e04\u0e23\u0e32\u0e07 \u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e22\u0e38\u0e14\u0e25\u0e07<\/p>\n<p>\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e32\u0e41\u0e19\u0e1a\u0e0a\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19 \u0e04\u0e27\u0e22\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e02\u0e37\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e33\u0e14\u0e31\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e39\u0e2b\u0e35\u0e08\u0e19\u0e2a\u0e38\u0e14\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e04\u0e27\u0e22\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e43\u0e19\u0e43\u0e2a\u0e48\u0e23\u0e39\u0e2b\u0e35\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e08\u0e19\u0e40\u0e22\u0e34\u0e49\u0e21\u0e09\u0e48\u0e33 \u0e40\u0e02\u0e32\u0e04\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e49\u0e19\u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e04\u0e27\u0e22\u0e2d\u0e48\u0e2d\u0e19\u0e04\u0e32\u0e23\u0e39\u0e2b\u0e35 \u0e08\u0e36\u0e07\u0e04\u0e48\u0e2d\u0e22\u0e46 \u0e14\u0e36\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35\u0e19\u0e31\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e1a\u0e25\u0e48\u0e2d\u0e07\u0e25\u0e2d\u0e22\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e2a\u0e31\u0e01\u0e41\u0e2b\u0e48\u0e07 \u0e44\u0e21\u0e48\u0e04\u0e34\u0e14\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e04\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e08\u0e30\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e19\u0e32\u0e14\u0e19\u0e35\u0e49<\/p>\n<p>\u0e41\u0e25\u0e30\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e09\u0e31\u0e19\u0e01\u0e47\u0e41\u0e17\u0e1a\u0e08\u0e30\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e40\u0e25\u0e22\u0e40\u0e27\u0e25\u0e32\u0e40\u0e07\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e40\u0e07\u0e35\u0e48\u0e22\u0e19\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e09\u0e31\u0e19<\/p>\n<p>\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e04\u0e1a\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e22\u0e47\u0e14\u0e01\u0e31\u0e19\u0e41\u0e17\u0e1a\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e01\u0e47\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49 \u0e1a\u0e32\u0e07\u0e27\u0e31\u0e19\u0e2a\u0e2d\u0e07\u0e2a\u0e32\u0e21\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e0b\u0e49\u0e33<\/p>\n<p>\u0e01\u0e47\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e23\u0e39\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32\u0e21\u0e35\u0e41\u0e1f\u0e19\u0e40\u0e14\u0e47\u0e01\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e19\u0e35\u0e48\u0e40\u0e2d\u0e07 \u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e32\u0e2a\u0e19\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e09\u0e31\u0e19\u0e01\u0e47\u0e41\u0e25\u0e49\u0e27\u0e01\u0e31\u0e19<\/p>\n<p>\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e49\u0e27\u0e22\u0e31\u0e07\u0e40\u0e08\u0e2d\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e35\u0e49\u0e40\u0e22\u0e47\u0e14\u0e2d\u0e35\u0e01 \u0e42\u0e0a\u0e04\u0e2a\u0e2d\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e2a\u0e38\u0e14\u0e46 \u0e44\u0e1b\u0e40\u0e25\u0e22<\/p>\n<p>\u0e08\u0e1a<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a \u0e01\u0e48\u0e2d [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sex-stories"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a<\/title>\n<meta name=\"description\" content=\"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e25\u0e32\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e2b\u0e19\u0e35\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e21\u0e32\u0e2b\u0e32\u0e07\u0e32\u0e19\u0e17\u0e33\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xzeeds.com\/\u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e25\u0e32\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e2b\u0e19\u0e35\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e21\u0e32\u0e2b\u0e32\u0e07\u0e32\u0e19\u0e17\u0e33\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xzeeds.com\/\u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\/\" \/>\n<meta property=\"og:site_name\" content=\"XZEEDS.COM\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-05T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"XZEEDS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"XZEEDS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/\"},\"author\":{\"name\":\"XZEEDS\",\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#\\\/schema\\\/person\\\/4a8418bf8cf45b4b47663a0ca68649f1\"},\"headline\":\"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e31\u0e1a\u0e40\u0e22\u0e47\u0e14\u0e08\u0e19\u0e19\u0e49\u0e33\u0e41\u0e15\u0e01\u0e04\u0e32\u0e23\u0e39\u0e2b\u0e35\",\"datePublished\":\"2022-11-05T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xzeeds.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg\",\"articleSection\":[\"SEX STORIES\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/\",\"url\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/\",\"name\":\"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xzeeds.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg\",\"datePublished\":\"2022-11-05T05:00:00+00:00\",\"description\":\"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e25\u0e32\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e2b\u0e19\u0e35\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e21\u0e32\u0e2b\u0e32\u0e07\u0e32\u0e19\u0e17\u0e33\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xzeeds.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg\",\"contentUrl\":\"https:\\\/\\\/xzeeds.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xzeeds.com\\\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"HOME\",\"item\":\"https:\\\/\\\/xzeeds.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEX STORIES\",\"item\":\"https:\\\/\\\/xzeeds.com\\\/sex-stories\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e31\u0e1a\u0e40\u0e22\u0e47\u0e14\u0e08\u0e19\u0e19\u0e49\u0e33\u0e41\u0e15\u0e01\u0e04\u0e32\u0e23\u0e39\u0e2b\u0e35\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#website\",\"url\":\"https:\\\/\\\/xzeeds.com\\\/\",\"name\":\"XZEEDS.COM\",\"description\":\"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e2d\u0e48\u0e32\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\",\"publisher\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#organization\"},\"alternateName\":\"XZEEDS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xzeeds.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#organization\",\"name\":\"XZEEDS.COM\",\"alternateName\":\"XZEEDS\",\"url\":\"https:\\\/\\\/xzeeds.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/xzeeds.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/XZEEDS-ICON.png\",\"contentUrl\":\"https:\\\/\\\/xzeeds.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/XZEEDS-ICON.png\",\"width\":256,\"height\":256,\"caption\":\"XZEEDS.COM\"},\"image\":{\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xzeeds.com\\\/#\\\/schema\\\/person\\\/4a8418bf8cf45b4b47663a0ca68649f1\",\"name\":\"XZEEDS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c20687cb151154ce632f29515e465715f0d7eba3325355d7663ced217ed8319d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c20687cb151154ce632f29515e465715f0d7eba3325355d7663ced217ed8319d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c20687cb151154ce632f29515e465715f0d7eba3325355d7663ced217ed8319d?s=96&d=mm&r=g\",\"caption\":\"XZEEDS\"},\"sameAs\":[\"https:\\\/\\\/xzeeds.com\\\/\",\"admin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a","description":"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e25\u0e32\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e2b\u0e19\u0e35\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e21\u0e32\u0e2b\u0e32\u0e07\u0e32\u0e19\u0e17\u0e33\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xzeeds.com\/\u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a","og_description":"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e25\u0e32\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e2b\u0e19\u0e35\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e21\u0e32\u0e2b\u0e32\u0e07\u0e32\u0e19\u0e17\u0e33\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23","og_url":"https:\/\/xzeeds.com\/\u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\/","og_site_name":"XZEEDS.COM","article_published_time":"2022-11-05T05:00:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg","type":"image\/jpeg"}],"author":"XZEEDS","twitter_card":"summary_large_image","twitter_misc":{"Written by":"XZEEDS","Est. reading time":"2 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/#article","isPartOf":{"@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/"},"author":{"name":"XZEEDS","@id":"https:\/\/xzeeds.com\/#\/schema\/person\/4a8418bf8cf45b4b47663a0ca68649f1"},"headline":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e31\u0e1a\u0e40\u0e22\u0e47\u0e14\u0e08\u0e19\u0e19\u0e49\u0e33\u0e41\u0e15\u0e01\u0e04\u0e32\u0e23\u0e39\u0e2b\u0e35","datePublished":"2022-11-05T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/"},"wordCount":5,"publisher":{"@id":"https:\/\/xzeeds.com\/#organization"},"image":{"@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg","articleSection":["SEX STORIES"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/","url":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/","name":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a","isPartOf":{"@id":"https:\/\/xzeeds.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/#primaryimage"},"image":{"@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg","datePublished":"2022-11-05T05:00:00+00:00","description":"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e09\u0e31\u0e19\u0e25\u0e32\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e2b\u0e19\u0e35\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e21\u0e32\u0e2b\u0e32\u0e07\u0e32\u0e19\u0e17\u0e33\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e01\u0e23","breadcrumb":{"@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/#primaryimage","url":"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg","contentUrl":"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/11\/\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27-15.jpg","width":1200,"height":800,"caption":"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27"},{"@type":"BreadcrumbList","@id":"https:\/\/xzeeds.com\/%e0%b9%82%e0%b8%94%e0%b8%99%e0%b8%84%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b8%a5%e0%b8%b1%e0%b8%81%e0%b8%ab%e0%b8%a5%e0%b8%b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"HOME","item":"https:\/\/xzeeds.com\/"},{"@type":"ListItem","position":2,"name":"SEX STORIES","item":"https:\/\/xzeeds.com\/sex-stories\/"},{"@type":"ListItem","position":3,"name":"\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e2a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01 \u0e42\u0e14\u0e19\u0e04\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e22\u0e43\u0e2b\u0e0d\u0e48\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e1a \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e31\u0e1a\u0e40\u0e22\u0e47\u0e14\u0e08\u0e19\u0e19\u0e49\u0e33\u0e41\u0e15\u0e01\u0e04\u0e32\u0e23\u0e39\u0e2b\u0e35"}]},{"@type":"WebSite","@id":"https:\/\/xzeeds.com\/#website","url":"https:\/\/xzeeds.com\/","name":"XZEEDS.COM","description":"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e2d\u0e48\u0e32\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e35\u0e22\u0e27 \u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19","publisher":{"@id":"https:\/\/xzeeds.com\/#organization"},"alternateName":"XZEEDS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xzeeds.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/xzeeds.com\/#organization","name":"XZEEDS.COM","alternateName":"XZEEDS","url":"https:\/\/xzeeds.com\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/xzeeds.com\/#\/schema\/logo\/image\/","url":"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/10\/XZEEDS-ICON.png","contentUrl":"https:\/\/xzeeds.com\/wp-content\/uploads\/2022\/10\/XZEEDS-ICON.png","width":256,"height":256,"caption":"XZEEDS.COM"},"image":{"@id":"https:\/\/xzeeds.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/xzeeds.com\/#\/schema\/person\/4a8418bf8cf45b4b47663a0ca68649f1","name":"XZEEDS","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/c20687cb151154ce632f29515e465715f0d7eba3325355d7663ced217ed8319d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c20687cb151154ce632f29515e465715f0d7eba3325355d7663ced217ed8319d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c20687cb151154ce632f29515e465715f0d7eba3325355d7663ced217ed8319d?s=96&d=mm&r=g","caption":"XZEEDS"},"sameAs":["https:\/\/xzeeds.com\/","admin"]}]}},"_links":{"self":[{"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/posts\/4279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/comments?post=4279"}],"version-history":[{"count":0,"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/posts\/4279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/media\/4280"}],"wp:attachment":[{"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/media?parent=4279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/categories?post=4279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xzeeds.com\/wp-json\/wp\/v2\/tags?post=4279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}